{"id":265037,"date":"2025-11-26T10:58:04","date_gmt":"2025-11-26T09:58:04","guid":{"rendered":"https:\/\/montedellevigne.it\/?page_id=265037"},"modified":"2026-03-23T14:26:56","modified_gmt":"2026-03-23T13:26:56","slug":"lambrusco-bio-base-nutriscore","status":"publish","type":"page","link":"https:\/\/montedellevigne.it\/en\/lambrusco-bio-base-nutriscore\/","title":{"rendered":"LAMBRUSCO BASE BIO NUTRISCORE"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/montedellevigne.it\/wp-content\/uploads\/2020\/05\/MdV-logo-trasp-no-foglia.png&#8221; title_text=&#8221;MdV logo trasp no foglia&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;200px&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Testo&#8221; _builder_version=&#8221;4.27.6&#8243; header_3_text_color=&#8221;#C09E56&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; text_orientation=&#8221;justified&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\">NUTRISCORE<\/h1>\n<h1 style=\"text-align: center;\">LAMBRUSCO BASE<\/h1>\n<h1 style=\"text-align: center;\">IGT EMILIA<\/h1>\n<h1 style=\"text-align: center;\">FRIZZANTE BIO<\/h1>\n<h1 style=\"text-align: center;\">\u00a0<\/h1>\n<h1 style=\"text-align: center;\">\u00a0<\/h1>\n<p>&nbsp;<\/p>\n<p>Ingredienti: Uve biologiche, gomma arabica,metabisolfito di potassio<\/p>\n<p>LOTTO: L.28\/25 -07\/26<\/p>\n<p>&nbsp;<\/p>\n<table class=\"CookieDeclarationTable\" style=\"width: 100%;\">\n<colgroup>\n<col \/>\n<col \/>\n<col \/>\n<col \/>\n<col \/><\/colgroup>\n<thead>\n<tr style=\"height: 24px;\">\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" style=\"width: 362.094px; height: 24px;\" scope=\"col\">TIPOLOGIA<\/th>\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" style=\"width: 441.906px; height: 24px;\" scope=\"col\">VALORI<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"height: 48px;\">\n<td class=\"CookieDeclarationTableCell\" style=\"width: 362.094px; height: 48px;\" title=\"In attesa\">\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 18px;\">Titolo alcolimetrico volumico effettivo<\/span><\/p>\n<p>Actual alcoholic strength by volume<\/p>\n<p>Titre alcoom\u00e9trique volumique r\u00e9el<\/p>\n<p>Grado alcoh\u00f3lico volum\u00e9trico adquirido<span style=\"font-size: 18px;\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<td class=\"CookieDeclarationTableCell\" style=\"width: 441.906px; height: 48px;\" title=\"Persistent\">\u00a011% Vol. a 20\u00b0 C<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"CookieDeclarationTableCell\" style=\"width: 362.094px; height: 24px;\" title=\"Utilizzato da Google DoubleClick per registrare e produrre resoconti sulle azioni dell'utente sul sito dopo aver visualizzato o cliccato una delle pubblicit\u00e0 dell'inserzionista al fine di misurare l'efficacia di una pubblicit\u00e0 e presentare pubblicit\u00e0 mirata all'utente.\">\n<p>Valore energetico (kcal)<\/p>\n<p>Energy value (kcal)<\/p>\n<p>Valeur \u00e9nerg\u00e9tique (kcal)<\/p>\n<p>Valor energ\u00e9tico (kcal)<\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<td class=\"CookieDeclarationTableCell\" style=\"width: 441.906px; height: 24px;\" title=\"1 anno\">\u00a072Kcal\/100 ml<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"CookieDeclarationTableCell\" style=\"width: 362.094px; height: 24px;\" title=\"Registra un ID univoco utilizzato da Google per statistiche legate a come il visitatore utilizza i video YouTube su diversi siti internet.\">\n<p>Valore energetico (kJ)<\/p>\n<p>Energy value (kJ)<\/p>\n<p>Valeur \u00e9nerg\u00e9tique (kJ)<\/p>\n<p>Valor energ\u00e9tico<span style=\"font-size: 18px;\"> (kJ)<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<td class=\"CookieDeclarationTableCell\" style=\"width: 441.906px; height: 24px;\" title=\"8 mesi\">\u00a0303Kj\/100 ml<\/td>\n<\/tr>\n<tr style=\"height: 18px;\">\n<td class=\"CookieDeclarationTableCell\" style=\"width: 362.094px; height: 18px;\" title=\"Questo cookie viene utilizzato per inviare dati a Google Analytics sul dispositivo e comportamento del visitatore. Traccia il visitatore su diversi dispositivi e canali di marketing.\">\n<p>Grassi Totali<\/p>\n<p>Total Fats<\/p>\n<p>Graisses totales<\/p>\n<p>Grasas totales<span style=\"font-size: 18px;\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<td class=\"CookieDeclarationTableCell\" style=\"width: 441.906px; height: 18px;\" title=\"Session\">N.D.\u00a0 gr\/100 ml<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"CookieDeclarationTableCell\" style=\"width: 362.094px; height: 24px;\" title=\"Utilizzato per verificare se il browser dell'utente supporta i cookie.\">\n<p>Grassi Totali<\/p>\n<p>Total Fats (of which saturated)<\/p>\n<p>Graisses totales (dont satur\u00e9s)<\/p>\n<p>Grasas totales<span style=\"font-size: 18px;\"> (de los cuales saturados)<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<td class=\"CookieDeclarationTableCell\" style=\"width: 441.906px; height: 24px;\" title=\"1 giorno\">N.D. gr\/100 ml<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"CookieDeclarationTableCell\" style=\"width: 362.094px; height: 24px;\" title=\"Aggiorna il contatore delle funzioni di condivisione sociale del sito.\">\n<p>Carboidrati totali<\/p>\n<p>Total carbohydrates<\/p>\n<p>Glucides totaux<\/p>\n<p>Hidratos de carbono totales<\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<td class=\"CookieDeclarationTableCell\" style=\"width: 441.906px; height: 24px;\" title=\"1 giorno\">\u00a01.4gr\/100 ml<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"CookieDeclarationTableCell\" style=\"width: 362.094px; height: 24px;\" title=\"Prova a stimare la velocit\u00e0 della connessione dell'utente su pagine con video YouTube integrati.\">\n<p>Carboidrati (di cui zuccheri)<\/p>\n<p>Total carbohydrates (of which sugars)<\/p>\n<p>Glucides totaux (dont sucres)<\/p>\n<p>Hidratos de carbono totales (de los cuales az\u00facares)<\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<td class=\"CookieDeclarationTableCell\" style=\"width: 441.906px; height: 24px;\" title=\"179 giorni\">0,8gr\/100 ml<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"CookieDeclarationTableCell\" style=\"width: 362.094px; height: 24px;\" title=\"Registra un ID univoco per statistiche legate a quali video YouTube sono stati visualizzati dall'utente.\">\n<p>Proteine<\/p>\n<p>Proteina<\/p>\n<p>Prot\u00e9ine<span style=\"font-size: 18px;\">\u00a0<\/span><\/p>\n<p>Prote\u00ednas<\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<td class=\"CookieDeclarationTableCell\" style=\"width: 441.906px; height: 24px;\" title=\"Session\">N.D. gr\/100 ml<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"CookieDeclarationTableCell\" style=\"width: 362.094px; height: 24px;\" title=\"Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato\">\n<p>Sale (NaCl)<\/p>\n<p>Salt\u00a0 (NaCl)<\/p>\n<p>Sel (NaCl)<\/p>\n<p>Sal (NaCl)<\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<td class=\"CookieDeclarationTableCell\" style=\"width: 441.906px; height: 24px;\" title=\"Session\">N.D. gr\/100 ml<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"CookieDeclarationTableCell\" style=\"width: 362.094px; height: 24px;\" title=\"Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato\">\n<p>Sodio (Na)<\/p>\n<p>Sodium (Na)<\/p>\n<\/td>\n<td class=\"CookieDeclarationTableCell\" style=\"width: 441.906px; height: 24px;\" title=\"Persistent\">N.D. gr\/100 ml<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Istruzioni per lo smaltimento<\/h1>\n<h2>Disposal instructions<\/h2>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/montedellevigne.it\/wp-content\/uploads\/2024\/02\/smaltimento.png&#8221; title_text=&#8221;smaltimento&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; NUTRISCORE LAMBRUSCO BASE IGT EMILIA FRIZZANTE BIO \u00a0 \u00a0 &nbsp; Ingredienti: Uve biologiche, gomma arabica,metabisolfito di potassio LOTTO: L.28\/25 -07\/26 &nbsp; TIPOLOGIA VALORI &nbsp; Titolo alcolimetrico volumico effettivo Actual alcoholic strength by volume Titre alcoom\u00e9trique volumique r\u00e9el Grado alcoh\u00f3lico volum\u00e9trico adquirido\u00a0 &nbsp; \u00a011% Vol. a 20\u00b0 C Valore energetico (kcal) Energy value (kcal) Valeur [&hellip;]<\/p>\n","protected":false},"author":3041,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"[vc_row css=\".vc_custom_1567678786043{padding-top: 60px !important;}\"][vc_column][vc_column_text css=\".vc_custom_1568129797239{margin-top: 20px !important;}\" el_class=\"wine-title\"]\r\n<h5 class=\"p1\" style=\"text-align: center; margin-bottom: 40px;\"><i>COOKIE POLICY<\/i><\/h5>\r\n<div>\r\n<div class=\"CookieDeclaration\" dir=\"ltr\" lang=\"it\">\r\n<p class=\"CookieDeclarationDialogText\">Questo sito web utilizza i cookie. Utilizziamo i cookie per personalizzare contenuti ed annunci, per fornire funzionalit\u00e0 dei social media e per analizzare il nostro traffico. Condividiamo inoltre informazioni sul modo in cui utilizza il nostro sito con i nostri partner che si occupano di analisi dei dati web, pubblicit\u00e0 e social media, i quali potrebbero combinarle con altre informazioni che ha fornito loro o che hanno raccolto dal suo utilizzo dei loro servizi. Acconsenta ai nostri cookie se continua ad utilizzare il nostro sito web.<\/p>\r\n<p class=\"CookieDeclarationIntro\">I cookie sono piccoli file di testo che possono essere utilizzati dai siti web per rendere pi\u00f9 efficiente l'esperienza per l'utente.<\/p>\r\nLa legge afferma che possiamo memorizzare i cookie sul suo dispositivo se sono strettamente necessari per il funzionamento di questo sito. Per tutti gli altri tipi di cookie abbiamo bisogno del suo permesso.\r\n\r\nQuesto sito utilizza diversi tipi di cookie. Alcuni cookie sono collocate da servizi di terzi che compaiono sulle nostre pagine.\r\n\r\nIn qualsiasi momento \u00e8 possibile modificare o revocare il proprio consenso dalla Dichiarazione dei cookie sul nostro sito Web.\r\n\r\nScopra di pi\u00f9 su chi siamo, come pu\u00f2 contattarci e come trattiamo i dati personali nella nostra <a href=\"https:\/\/montedellevigne.it\/privacy-policy\/\">Informativa sulla privacy.<\/a>\r\n\r\nIl suo consenso si applica ai seguenti siti web: montedellevigne.it\r\n\r\n<\/div>\r\n<\/div>\r\n[\/vc_column_text][vc_column_text css=\".vc_custom_1567153550976{margin-top: 20px !important;}\" el_class=\"wine-title\"]\r\n<p class=\"CookieDeclarationTypeHeader\"><strong>Necessario (6)<\/strong><\/p>\r\n<p class=\"CookieDeclarationTypeDescription\">I cookie necessari aiutano a contribuire a rendere fruibile un sito web abilitando le funzioni di base come la navigazione della pagina e l'accesso alle aree protette del sito. Il sito web non pu\u00f2 funzionare correttamente senza questi cookie.<\/p>\r\n\r\n<table class=\"CookieDeclarationTable\"><colgroup> <col \/> <col \/> <col \/> <col \/> <col \/><\/colgroup>\r\n<thead>\r\n<tr>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Nome<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Fornitore<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Scopo<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Scadenza<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Tipo<\/th>\r\n<\/tr>\r\n<\/thead>\r\n<tbody>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"__cfduid [x2] \">__cfduid [x2]<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"addtoany.com, cdn-immedia.net\">addtoany.com\r\ncdn-immedia.net<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Utilizzato dalla rete di contenuti, Cloudflare, per identificare traffico web affidabile.\">Utilizzato dalla rete di contenuti, Cloudflare, per identificare traffico web affidabile.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"1 anno\">1 anno<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"CookieConsent\">CookieConsent<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"www.studiocru.com\/demo\/demo1\">montedellevigne.it<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Memorizza lo stato del consenso ai cookie dell'utente per il dominio corrente\">Memorizza lo stato del consenso ai cookie dell'utente per il dominio corrente<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"1 anno\">1 anno<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"has_js\">has_js<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"www.studiocru.com\/demo\/demo1\">montedellevigne.it<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Registra se l'utente ha attivato o meno JavaScript nel browser.\">Registra se l'utente ha attivato o meno JavaScript nel browser.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Session\">Session<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"language\">language<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"www.studiocru.com\/demo\/demo1\">montedellevigne.it<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Salva la lingua preferita dell'utente sul sito internet.\">Salva la lingua preferita dell'utente sul sito internet.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"1 anno\">1 anno<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"local_storage_support_test\">local_storage_support_test<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"twitter.com\">twitter.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Il cookie viene utilizzato contestualmente alla funzione di archiviazione locale nel browser. Questa funzione consente al sito di caricarsi pi\u00f9 velocemente pre-caricando determinate procedure. \">Il cookie viene utilizzato contestualmente alla funzione di archiviazione locale nel browser. Questa funzione consente al sito di caricarsi pi\u00f9 velocemente pre-caricando determinate procedure.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Persistent\">Persistent<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTML Local Storage\">HTML Local Storage<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n[\/vc_column_text][vc_column_text css=\".vc_custom_1567153559412{margin-top: 20px !important;}\" el_class=\"wine-title\"]\r\n<p class=\"CookieDeclarationTypeHeader\"><strong>Statistiche (5)<\/strong><\/p>\r\n<p class=\"CookieDeclarationTypeDescription\">I cookie statistici aiutano i proprietari del sito web a capire come i visitatori interagiscono con i siti raccogliendo e trasmettendo informazioni in forma anonima.<\/p>\r\n\r\n<table class=\"CookieDeclarationTable\"><colgroup> <col \/> <col \/> <col \/> <col \/> <col \/><\/colgroup>\r\n<thead>\r\n<tr>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Nome<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Fornitore<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Scopo<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Scadenza<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Tipo<\/th>\r\n<\/tr>\r\n<\/thead>\r\n<tbody>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"_dc_gtm_UA-#\">_dc_gtm_UA-#<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"www.studiocru.com\/demo\/demo1\">montedellevigne.it<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Utilizzato dal Google Tag Manager per controllare il caricamento di uno script tag di Google Analytics.\">Utilizzato dal Google Tag Manager per controllare il caricamento di uno script tag di Google Analytics.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"1 giorno\">1 giorno<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"_ga\">_ga<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"www.studiocru.com\/demo\/demo1\">montedellevigne.it<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Registra un ID univoco utilizzato per generare dati statistici su come il visitatore utilizza il sito internet.\">Registra un ID univoco utilizzato per generare dati statistici su come il visitatore utilizza il sito internet.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"2 anni\">2 anni<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"_gid\">_gid<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"www.studiocru.com\/demo\/demo1\">montedellevigne.it<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Registra un ID univoco utilizzato per generare dati statistici su come il visitatore utilizza il sito internet.\">Registra un ID univoco utilizzato per generare dati statistici su come il visitatore utilizza il sito internet.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"1 giorno\">1 giorno<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"collect\">collect<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"google-analytics.com\">google-analytics.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Usato per inviare a Google Analytics dati riguardo il device e il comportamento del visitatore. Segue il visitatore attraverso i device e i canali di marketing.\">Usato per inviare a Google Analytics dati riguardo il device e il comportamento del visitatore. Segue il visitatore attraverso i device e i canali di marketing.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Session\">Session<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Pixel Tracker\">Pixel Tracker<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"p.gif\">p.gif<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"typekit.net\">typekit.net<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Tiene traccia dei caratteri speciali utilizzati sul sito web per l'analisi interna. Il cookie non registra alcun dato di visitatore. \">Tiene traccia dei caratteri speciali utilizzati sul sito web per l'analisi interna. Il cookie non registra alcun dato di visitatore.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Session\">Session<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Pixel Tracker\">Pixel Tracker<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n[\/vc_column_text][vc_column_text css=\".vc_custom_1567153570168{margin-top: 20px !important;}\" el_class=\"wine-title\"]\r\n<p class=\"CookieDeclarationTypeHeader\"><strong>Marketing (15)<\/strong><\/p>\r\n<p class=\"CookieDeclarationTypeDescription\">I cookie per il marketing vengono utilizzati per monitorare i visitatori nei siti web. L'intento \u00e8 quello di visualizzare annunci pertinenti e coinvolgenti per il singolo utente e quindi quelli di maggior valore per gli editori e gli inserzionisti terzi.<\/p>\r\n\r\n<table class=\"CookieDeclarationTable\"><colgroup> <col \/> <col \/> <col \/> <col \/> <col \/><\/colgroup>\r\n<thead>\r\n<tr>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Nome<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Fornitore<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Scopo<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Scadenza<\/th>\r\n<th class=\"CookieDeclarationTableHeader\" dir=\"ltr\" scope=\"col\">Tipo<\/th>\r\n<\/tr>\r\n<\/thead>\r\n<tbody>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"__widgetsettings\">__widgetsettings<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"twitter.com\">twitter.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"In attesa\">In attesa<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Persistent\">Persistent<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTML Local Storage\">HTML Local Storage<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"GPS\">GPS<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"youtube.com\">youtube.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Registra un ID univoco sui dispositivi mobile per consentire il tracciamento sulla base della posizione geografica GPS.\">Registra un ID univoco sui dispositivi mobile per consentire il tracciamento sulla base della posizione geografica GPS.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"1 giorno\">1 giorno<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"IDE\">IDE<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"doubleclick.net\">doubleclick.net<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Utilizzato da Google DoubleClick per registrare e produrre resoconti sulle azioni dell'utente sul sito dopo aver visualizzato o cliccato una delle pubblicit\u00e0 dell'inserzionista al fine di misurare l'efficacia di una pubblicit\u00e0 e presentare pubblicit\u00e0 mirata all'utente.\">Utilizzato da Google DoubleClick per registrare e produrre resoconti sulle azioni dell'utente sul sito dopo aver visualizzato o cliccato una delle pubblicit\u00e0 dell'inserzionista al fine di misurare l'efficacia di una pubblicit\u00e0 e presentare pubblicit\u00e0 mirata all'utente.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"1 anno\">1 anno<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"PREF\">PREF<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"youtube.com\">youtube.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Registra un ID univoco utilizzato da Google per statistiche legate a come il visitatore utilizza i video YouTube su diversi siti internet.\">Registra un ID univoco utilizzato da Google per statistiche legate a come il visitatore utilizza i video YouTube su diversi siti internet.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"8 mesi\">8 mesi<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"r\/collect\">r\/collect<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"doubleclick.net\">doubleclick.net<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Questo cookie viene utilizzato per inviare dati a Google Analytics sul dispositivo e comportamento del visitatore. Traccia il visitatore su diversi dispositivi e canali di marketing.\">Questo cookie viene utilizzato per inviare dati a Google Analytics sul dispositivo e comportamento del visitatore. Traccia il visitatore su diversi dispositivi e canali di marketing.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Session\">Session<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Pixel Tracker\">Pixel Tracker<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"test_cookie\">test_cookie<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"doubleclick.net\">doubleclick.net<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Utilizzato per verificare se il browser dell'utente supporta i cookie.\">Utilizzato per verificare se il browser dell'utente supporta i cookie.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"1 giorno\">1 giorno<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"uvc\">uvc<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"addtoany.com\">addtoany.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Aggiorna il contatore delle funzioni di condivisione sociale del sito.\">Aggiorna il contatore delle funzioni di condivisione sociale del sito.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"1 giorno\">1 giorno<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"VISITOR_INFO1_LIVE\">VISITOR_INFO1_LIVE<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"youtube.com\">youtube.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Prova a stimare la velocit\u00e0 della connessione dell'utente su pagine con video YouTube integrati.\">Prova a stimare la velocit\u00e0 della connessione dell'utente su pagine con video YouTube integrati.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"179 giorni\">179 giorni<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"YSC\">YSC<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"youtube.com\">youtube.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Registra un ID univoco per statistiche legate a quali video YouTube sono stati visualizzati dall'utente.\">Registra un ID univoco per statistiche legate a quali video YouTube sono stati visualizzati dall'utente.<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Session\">Session<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTTP Cookie\">HTTP Cookie<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"yt-remote-cast-installed\">yt-remote-cast-installed<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"youtube.com\">youtube.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato\">Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Session\">Session<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTML Local Storage\">HTML Local Storage<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"yt-remote-connected-devices\">yt-remote-connected-devices<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"youtube.com\">youtube.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato\">Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Persistent\">Persistent<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTML Local Storage\">HTML Local Storage<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"yt-remote-device-id\">yt-remote-device-id<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"youtube.com\">youtube.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato\">Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Persistent\">Persistent<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTML Local Storage\">HTML Local Storage<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"yt-remote-fast-check-period\">yt-remote-fast-check-period<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"youtube.com\">youtube.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato\">Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Session\">Session<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTML Local Storage\">HTML Local Storage<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"yt-remote-session-app\">yt-remote-session-app<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"youtube.com\">youtube.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato\">Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Session\">Session<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTML Local Storage\">HTML Local Storage<\/td>\r\n<\/tr>\r\n<tr>\r\n<td class=\"CookieDeclarationTableCell\" title=\"yt-remote-session-name\">yt-remote-session-name<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"youtube.com\">youtube.com<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato\">Memorizza le preferenze del lettore video dell'utente usando il video YouTube incorporato<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"Session\">Session<\/td>\r\n<td class=\"CookieDeclarationTableCell\" title=\"HTML Local Storage\">HTML Local Storage<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n[\/vc_column_text][\/vc_column][\/vc_row]","_et_gb_content_width":"","footnotes":""},"class_list":["post-265037","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LAMBRUSCO BASE BIO NUTRISCORE - Monte delle Vigne<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montedellevigne.it\/en\/lambrusco-bio-base-nutriscore\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LAMBRUSCO BASE BIO NUTRISCORE - Monte delle Vigne\" \/>\n<meta property=\"og:description\" content=\"&nbsp; NUTRISCORE LAMBRUSCO BASE IGT EMILIA FRIZZANTE BIO \u00a0 \u00a0 &nbsp; Ingredienti: Uve biologiche, gomma arabica,metabisolfito di potassio LOTTO: L.28\/25 -07\/26 &nbsp; TIPOLOGIA VALORI &nbsp; Titolo alcolimetrico volumico effettivo Actual alcoholic strength by volume Titre alcoom\u00e9trique volumique r\u00e9el Grado alcoh\u00f3lico volum\u00e9trico adquirido\u00a0 &nbsp; \u00a011% Vol. a 20\u00b0 C Valore energetico (kcal) Energy value (kcal) Valeur [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montedellevigne.it\/en\/lambrusco-bio-base-nutriscore\/\" \/>\n<meta property=\"og:site_name\" content=\"Monte delle Vigne\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T13:26:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/lambrusco-bio-base-nutriscore\\\/\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/lambrusco-bio-base-nutriscore\\\/\",\"name\":\"LAMBRUSCO BASE BIO NUTRISCORE - Monte delle Vigne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#website\"},\"datePublished\":\"2025-11-26T09:58:04+00:00\",\"dateModified\":\"2026-03-23T13:26:56+00:00\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montedellevigne.it\\\/lambrusco-bio-base-nutriscore\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/\",\"name\":\"Monte delle Vigne\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#organization\",\"name\":\"Monte delle Vigne\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/MdV-logo-trasp-no-foglia.png\",\"contentUrl\":\"https:\\\/\\\/montedellevigne.it\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/MdV-logo-trasp-no-foglia.png\",\"width\":393,\"height\":200,\"caption\":\"Monte delle Vigne\"},\"image\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LAMBRUSCO BASE BIO NUTRISCORE - Monte delle Vigne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montedellevigne.it\/en\/lambrusco-bio-base-nutriscore\/","og_locale":"en_GB","og_type":"article","og_title":"LAMBRUSCO BASE BIO NUTRISCORE - Monte delle Vigne","og_description":"&nbsp; NUTRISCORE LAMBRUSCO BASE IGT EMILIA FRIZZANTE BIO \u00a0 \u00a0 &nbsp; Ingredienti: Uve biologiche, gomma arabica,metabisolfito di potassio LOTTO: L.28\/25 -07\/26 &nbsp; TIPOLOGIA VALORI &nbsp; Titolo alcolimetrico volumico effettivo Actual alcoholic strength by volume Titre alcoom\u00e9trique volumique r\u00e9el Grado alcoh\u00f3lico volum\u00e9trico adquirido\u00a0 &nbsp; \u00a011% Vol. a 20\u00b0 C Valore energetico (kcal) Energy value (kcal) Valeur [&hellip;]","og_url":"https:\/\/montedellevigne.it\/en\/lambrusco-bio-base-nutriscore\/","og_site_name":"Monte delle Vigne","article_modified_time":"2026-03-23T13:26:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/montedellevigne.it\/lambrusco-bio-base-nutriscore\/","url":"https:\/\/montedellevigne.it\/lambrusco-bio-base-nutriscore\/","name":"LAMBRUSCO BASE BIO NUTRISCORE - Monte delle Vigne","isPartOf":{"@id":"https:\/\/montedellevigne.it\/it\/#website"},"datePublished":"2025-11-26T09:58:04+00:00","dateModified":"2026-03-23T13:26:56+00:00","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montedellevigne.it\/lambrusco-bio-base-nutriscore\/"]}]},{"@type":"WebSite","@id":"https:\/\/montedellevigne.it\/it\/#website","url":"https:\/\/montedellevigne.it\/it\/","name":"Monte delle Vigne","description":"","publisher":{"@id":"https:\/\/montedellevigne.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montedellevigne.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/montedellevigne.it\/it\/#organization","name":"Monte delle Vigne","url":"https:\/\/montedellevigne.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/montedellevigne.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/montedellevigne.it\/wp-content\/uploads\/2020\/05\/MdV-logo-trasp-no-foglia.png","contentUrl":"https:\/\/montedellevigne.it\/wp-content\/uploads\/2020\/05\/MdV-logo-trasp-no-foglia.png","width":393,"height":200,"caption":"Monte delle Vigne"},"image":{"@id":"https:\/\/montedellevigne.it\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/montedellevigne.it\/en\/wp-json\/wp\/v2\/pages\/265037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montedellevigne.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/montedellevigne.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/montedellevigne.it\/en\/wp-json\/wp\/v2\/users\/3041"}],"replies":[{"embeddable":true,"href":"https:\/\/montedellevigne.it\/en\/wp-json\/wp\/v2\/comments?post=265037"}],"version-history":[{"count":5,"href":"https:\/\/montedellevigne.it\/en\/wp-json\/wp\/v2\/pages\/265037\/revisions"}],"predecessor-version":[{"id":265294,"href":"https:\/\/montedellevigne.it\/en\/wp-json\/wp\/v2\/pages\/265037\/revisions\/265294"}],"wp:attachment":[{"href":"https:\/\/montedellevigne.it\/en\/wp-json\/wp\/v2\/media?parent=265037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}