{"id":248533,"date":"2023-06-10T22:00:01","date_gmt":"2023-06-10T20:00:01","guid":{"rendered":"https:\/\/montedellevigne.it\/?p=248533"},"modified":"2023-06-25T11:05:18","modified_gmt":"2023-06-25T09:05:18","slug":"degustazione-enoteca-manzato","status":"publish","type":"post","link":"https:\/\/montedellevigne.it\/it\/degustazione-enoteca-manzato\/","title":{"rendered":"Enoteca Manzato e Monte delle Vigne: una degustazione super!"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.0&#8243; background_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/montedellevigne.it\/wp-content\/uploads\/2023\/06\/Locandina-Enoteca-Manzato.jpeg&#8221; title_text=&#8221;Locandina Enoteca Manzato&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Una trasferta davvero ricca di soddisfazioni quella presso <strong><em>Enoteca Manzato<\/em><\/strong>\u00a0a Mariano Comense (CO) da parte di <em>Monte delle Vigne<\/em> grazie al lavoro di divulgazione e <em>story telling<\/em> di <em>Dino Centofante<\/em>, persona di riferimento per Como e Monza Brianza.<br \/>La degustazione si \u00e8 tenuta\u00a0<em>sabato 10 giugno<\/em>\u00a0<em>2023<\/em> ed \u00e8 stata all&#8217;insegna della scoperta dei vini di alta qualit\u00e0 prodotti da Monte delle Vigne.<\/p>\n<p>Durante la degustazione, che si \u00e8 svolta su due turni (17:00 e 18:30), gli intervenuti hanno avuto l&#8217;opportunit\u00e0 di assaggiare una selezione di etichette, accompagnate da deliziose specialit\u00e0 Emiliane come gnocco fritto e salumi, realizzate per\u00f2 in loco dal super team delle Signore <em>Marinella<\/em> e <em>Ornella<\/em>, sorelle di <em>Luca Lessi<\/em>, patron dell&#8217;enoteca Manzato.<\/p>\n<p>Il primo vino presentato dal Sig. <em>Dino<\/em>, di concerto con <em>Luca Lessi<\/em>, \u00e8 stata <a href=\"https:\/\/montedellevigne.it\/negozio\/vini\/bianchi\/malvasia-selezione\/\" target=\"_blank\" rel=\"noopener\"><em>Primavera<\/em><\/a>, spumante da uve <em>Malvasia di Candia Aromatica<\/em>, che stupisce per la sua freschezza e dinamicit\u00e0.<br \/>Il secondo vino in lista \u00e8 stata <a href=\"https:\/\/montedellevigne.it\/negozio\/vini\/bianchi\/ginestra-2021\/\" target=\"_blank\" rel=\"noopener\"><em>Ginestra<\/em><\/a>, la versione ferma e in acciaio della Malvasia, dal gusto fresco e delicato, con note di frutta esotica e fiori. La Malvasia si \u00e8 rivelata un vitigno molto versatile, adatto ad accompagnare il gnocco fritto, i salumi e i \u00a0formaggi freschi proposti.<br \/>Il terzo assaggiato \u00e8 stato il Lambrusco <a href=\"https:\/\/montedellevigne.it\/negozio\/vini\/lambrusco\/lambrusco-selezione\/\" target=\"_blank\" rel=\"noopener\"><em>Rio Valli<\/em><\/a>, lo spumante prodotto con uve Maestri e Grasparossa: spiritato, vinoso e con tanti rimandi ai frutti di bosco come mora e lampone.<br \/>Infine, il &#8220;campione&#8221; <a href=\"https:\/\/montedellevigne.it\/negozio\/vini\/rossi\/nabucco\/\" target=\"_blank\" rel=\"noopener\"><em>Nabucco<\/em><\/a> ha chiuso, con il suo sorso imperioso e la sua trama tannica complessa, il pomeriggio dedicato ai <em>Colli di Parma<\/em> e alla sua cantina di riferimento.<\/p>\n<p>&#8220;<em>Queste iniziative dovrebbero essere messe in atto ogni weekend<\/em>&#8220;, ha dichiarato <em>Lorenzo Numanti<\/em>.<br \/>&#8220;<em>Perch\u00e9 oltre a divulgare i nostri prodotti fuori da Parma, servono per consolidare il rapporto con persone come Luca Lessi, che danno fiducia ai nostri vini prima della &#8220;conferma&#8221; avvenuta poi dai suoi invitati<\/em>&#8220;.<\/p>\n<p>Un doveroso\u00a0<em>grazie<\/em> &#8211; quasi scontato &#8211; al Sig. <em>Dino Centofante<\/em> per il suo entusiasmo e a tutto lo staff dell&#8217;<em>Enoteca Manzato<\/em>.<\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=&#8221;248547,248548,248549,248550,248540,248551,248552,248553&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_gallery][et_pb_video src=&#8221;https:\/\/montedellevigne.it\/wp-content\/uploads\/2023\/06\/Video-Enoteca-Manzato.mp4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una trasferta davvero ricca di soddisfazioni quella presso Enoteca Manzato\u00a0a Mariano Comense (CO) da parte di Monte delle Vigne grazie al lavoro di divulgazione e story telling di Dino Centofante, persona di riferimento per Como e Monza Brianza.La degustazione si \u00e8 tenuta\u00a0sabato 10 giugno\u00a02023 ed \u00e8 stata all&#8217;insegna della scoperta dei vini di alta qualit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":2674,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p style=\"text-align: right;\">26 Ottobre 2022<\/p><p style=\"text-align: center;\"><em>\"Nabucco<\/em> <em>non celebra solo i suoi primi trent\u2019anni, ma anche l\u2019inizio di un lungo cammino che ha visto la nostra <\/em><em>azienda protagonista della produzione di vini biologici di qualit\u00e0, nel rispetto della sostenibilit\u00e0 e sostenuti da una forte passione, a partire da vitigni radicati nel territorio, e dal peculiare carattere fermo in controtendenza con i vini frizzanti tipici di questa terra. Una festa per il successo di un vino quindi che, fin dal nome, trasmette energia e tenacia, gli stessi valori dell\u2019opera verdiana che ha debuttato alla Scala di Milano<\/em><em> nel 1842\".<\/em><\/p><p style=\"text-align: center;\"><em>Paolo Pizzarotti<\/em><\/p><p><img class=\"wp-image-244534 aligncenter\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/f87e29ad-d34e-47f2-9b5c-9133a520e769-225x300.jpg\" alt=\"\" width=\"197\" height=\"262\" \/><\/p><p><strong><em>Nabucco<\/em><\/strong>, il vino simbolo dell\u2019azienda e<strong><em>\u00a0<\/em><\/strong>prodotto esclusivamente con uve Barbera e Merlot, celebra quest\u2019anno <strong>le trenta vendemmie<\/strong>. <em>Nabucco<\/em> \u00e8 una sintesi profonda dell\u2019identit\u00e0 della cantina: \u00e8 <strong>il primo vino<\/strong> nato in casa Monte delle Vigne, nel 1992, ed \u00e8 <strong>il primo rosso fermo<\/strong> realizzato a Parma, un territorio dove per tradizione dominano i frizzanti. Il nome del vino \u00e8 un omaggio al territorio parmense e al suo carattere legato al mondo lirico come citt\u00e0 della musica.<\/p><p>I vigneti con cui viene prodotto Nabucco hanno dai nove ai trent\u2019anni di et\u00e0 e crescono su <strong>terreni calcareo argillosi<\/strong> ad un\u2019altitudine di <strong>200\/300 metri<\/strong>. L\u2019<strong>uva Barbera <\/strong>viene selezionata e raccolta a mano e macera, dopo la fermentazione a 32\u00b0, \u00a030 giorni sulle bucce e <strong>affina poi 12\/14 mesi<\/strong><\/p><p>\u00a0<\/p><p style=\"text-align: left;\">Per festeggiare questo suo importante traguardo lo abbiamo reso protagonista di un pranzo esclusivo in una <strong>verticale senza tempo<\/strong>: <strong>una selezione di 5 annate<\/strong>, rappresentative delle migliori espressioni del percorso di Nabucco, in un gioco perfetto di sapori ed equilibri studiato dallo Chef de <strong>\"Il Luogo di Aimo e Nadia\"<\/strong><\/p><p><img class=\"wp-image-244700 aligncenter\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/12\/MONTE-DELLE-VIGNE-Nabucco-menu_pages-to-jpg-0001-300x206.jpg\" alt=\"\" width=\"172\" height=\"118\" \/><\/p><p style=\"text-align: center;\"><strong>Ripercorri con noi le tappe di questo <\/strong><\/p><p style=\"text-align: center;\"><strong>indimenticabile viaggio<\/strong><\/p>[caption id=\"attachment_244604\" align=\"aligncenter\" width=\"300\"]<img class=\"wp-image-244604 size-medium\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/cce2cb1f-2a61-460b-96ff-660c7e95e658-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> Cicerchie dei Monti Dauni con marasciuolo, oliva Nolca e lampascioni all\u2019aceto di lamponi - Nabucco 2018[\/caption][caption id=\"attachment_244602\" align=\"aligncenter\" width=\"300\"]<img class=\"wp-image-244602 size-medium\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/5bb5df04-d249-4964-b7b8-30ca7270baf5-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> Mousse di funghi porcini su pan brioche caldo - Nabucco 2015[\/caption][caption id=\"attachment_244600\" align=\"aligncenter\" width=\"300\"]<img class=\"wp-image-244600 size-medium\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/00a994aa-6547-44c9-a3af-ad9b2f149683-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> Tortelli farciti di ossobuco di Fassona e midollo e il suo ristretto allo zafferano sardo e parmigiano - Nabucco 2011[\/caption][caption id=\"attachment_244603\" align=\"aligncenter\" width=\"300\"]<img class=\"wp-image-244603 size-medium\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/a53ef983-2587-433a-aeb8-0c9311d91cc9-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> tortelli farciti di ossobuco di Fassona e midollo e il suo ristretto allo zafferano sardo e parmigiano - Nabucco 2005[\/caption][caption id=\"attachment_244601\" align=\"aligncenter\" width=\"300\"]<img class=\"wp-image-244601 size-medium\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/4cd15962-6ce4-4d5b-9433-89226abb8ac4-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> Anatra Apicius affumicata alle spezie con salsa di seppie - Nabucco 1998[\/caption]<p>\u00a0<\/p><p style=\"text-align: center;\"><strong>APPROFONDIMENTI<\/strong><\/p><p style=\"text-align: center;\"><a href=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/MONTE-DELLE-VIGNE-Nabucco-menu.pdf\" target=\"_blank\" rel=\"noopener\">MONTE DELLE VIGNE & iL LUOGO - Men\u00f9<\/a><\/p><p style=\"text-align: center;\"><a href=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/ANDAMENTO-ANNATE_def.pdf\">NABUCCO - ANDAMENTO ANNATE<\/a><\/p><p style=\"text-align: center;\"><strong>RASSEGNA STAMPA<\/strong><\/p><p style=\"text-align: center;\"><a href=\"https:\/\/www.civiltadelbere.com\/nabucco-di-monte-delle-vigne-racconta-i-suoi-primi-30-anni\/\" target=\"_blank\" rel=\"noopener\">CIVILTA' DEL BERE<\/a><\/p><p style=\"text-align: center;\"><a href=\"https:\/\/www.ilgolosario.it\/it\/monte-delle-vigne-lo-splendore-della-barbera\" target=\"_blank\" rel=\"noopener\">IL GOLOSARIO<\/a><\/p><p style=\"text-align: center;\"><a href=\"https:\/\/www.ioeilvino.it\/monte-delle-vigne-30-anni-di-nabucco\/\" target=\"_blank\" rel=\"noopener\">IOEILVINO.IT<\/a><\/p>","_et_gb_content_width":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-248533","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enoteca Manzato e Monte delle Vigne: una degustazione super! - Monte delle Vigne<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enoteca Manzato e Monte delle Vigne: una degustazione super! - Monte delle Vigne\" \/>\n<meta property=\"og:description\" content=\"Una trasferta davvero ricca di soddisfazioni quella presso Enoteca Manzato\u00a0a Mariano Comense (CO) da parte di Monte delle Vigne grazie al lavoro di divulgazione e story telling di Dino Centofante, persona di riferimento per Como e Monza Brianza.La degustazione si \u00e8 tenuta\u00a0sabato 10 giugno\u00a02023 ed \u00e8 stata all&#039;insegna della scoperta dei vini di alta qualit\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montedellevigne.it\/it\/degustazione-enoteca-manzato\/\" \/>\n<meta property=\"og:site_name\" content=\"Monte delle Vigne\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-10T20:00:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-25T09:05:18+00:00\" \/>\n<meta name=\"author\" content=\"mdv-editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mdv-editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/degustazione-enoteca-manzato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/degustazione-enoteca-manzato\\\/\"},\"author\":{\"name\":\"mdv-editor\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#\\\/schema\\\/person\\\/97c95fefce892f1b82cf733eb48064fd\"},\"headline\":\"Enoteca Manzato e Monte delle Vigne: una degustazione super!\",\"datePublished\":\"2023-06-10T20:00:01+00:00\",\"dateModified\":\"2023-06-25T09:05:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/degustazione-enoteca-manzato\\\/\"},\"wordCount\":480,\"publisher\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/degustazione-enoteca-manzato\\\/\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/degustazione-enoteca-manzato\\\/\",\"name\":\"Enoteca Manzato e Monte delle Vigne: una degustazione super! - Monte delle Vigne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#website\"},\"datePublished\":\"2023-06-10T20:00:01+00:00\",\"dateModified\":\"2023-06-25T09:05:18+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montedellevigne.it\\\/degustazione-enoteca-manzato\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/\",\"name\":\"Monte delle Vigne\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#organization\",\"name\":\"Monte delle Vigne\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/MdV-logo-trasp-no-foglia.png\",\"contentUrl\":\"https:\\\/\\\/montedellevigne.it\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/MdV-logo-trasp-no-foglia.png\",\"width\":393,\"height\":200,\"caption\":\"Monte delle Vigne\"},\"image\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#\\\/schema\\\/person\\\/97c95fefce892f1b82cf733eb48064fd\",\"name\":\"mdv-editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g\",\"caption\":\"mdv-editor\"},\"url\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/author\\\/mdv-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enoteca Manzato e Monte delle Vigne: una degustazione super! - Monte delle Vigne","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Enoteca Manzato e Monte delle Vigne: una degustazione super! - Monte delle Vigne","og_description":"Una trasferta davvero ricca di soddisfazioni quella presso Enoteca Manzato\u00a0a Mariano Comense (CO) da parte di Monte delle Vigne grazie al lavoro di divulgazione e story telling di Dino Centofante, persona di riferimento per Como e Monza Brianza.La degustazione si \u00e8 tenuta\u00a0sabato 10 giugno\u00a02023 ed \u00e8 stata all'insegna della scoperta dei vini di alta qualit\u00e0 [&hellip;]","og_url":"https:\/\/montedellevigne.it\/it\/degustazione-enoteca-manzato\/","og_site_name":"Monte delle Vigne","article_published_time":"2023-06-10T20:00:01+00:00","article_modified_time":"2023-06-25T09:05:18+00:00","author":"mdv-editor","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"mdv-editor","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montedellevigne.it\/degustazione-enoteca-manzato\/#article","isPartOf":{"@id":"https:\/\/montedellevigne.it\/degustazione-enoteca-manzato\/"},"author":{"name":"mdv-editor","@id":"https:\/\/montedellevigne.it\/it\/#\/schema\/person\/97c95fefce892f1b82cf733eb48064fd"},"headline":"Enoteca Manzato e Monte delle Vigne: una degustazione super!","datePublished":"2023-06-10T20:00:01+00:00","dateModified":"2023-06-25T09:05:18+00:00","mainEntityOfPage":{"@id":"https:\/\/montedellevigne.it\/degustazione-enoteca-manzato\/"},"wordCount":480,"publisher":{"@id":"https:\/\/montedellevigne.it\/it\/#organization"},"articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/montedellevigne.it\/degustazione-enoteca-manzato\/","url":"https:\/\/montedellevigne.it\/degustazione-enoteca-manzato\/","name":"Enoteca Manzato e Monte delle Vigne: una degustazione super! - Monte delle Vigne","isPartOf":{"@id":"https:\/\/montedellevigne.it\/it\/#website"},"datePublished":"2023-06-10T20:00:01+00:00","dateModified":"2023-06-25T09:05:18+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montedellevigne.it\/degustazione-enoteca-manzato\/"]}]},{"@type":"WebSite","@id":"https:\/\/montedellevigne.it\/it\/#website","url":"https:\/\/montedellevigne.it\/it\/","name":"Monte delle Vigne","description":"","publisher":{"@id":"https:\/\/montedellevigne.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montedellevigne.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/montedellevigne.it\/it\/#organization","name":"Monte delle Vigne","url":"https:\/\/montedellevigne.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/montedellevigne.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/montedellevigne.it\/wp-content\/uploads\/2020\/05\/MdV-logo-trasp-no-foglia.png","contentUrl":"https:\/\/montedellevigne.it\/wp-content\/uploads\/2020\/05\/MdV-logo-trasp-no-foglia.png","width":393,"height":200,"caption":"Monte delle Vigne"},"image":{"@id":"https:\/\/montedellevigne.it\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/montedellevigne.it\/it\/#\/schema\/person\/97c95fefce892f1b82cf733eb48064fd","name":"mdv-editor","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g","caption":"mdv-editor"},"url":"https:\/\/montedellevigne.it\/it\/author\/mdv-editor\/"}]}},"_links":{"self":[{"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/posts\/248533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/users\/2674"}],"replies":[{"embeddable":true,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/comments?post=248533"}],"version-history":[{"count":11,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/posts\/248533\/revisions"}],"predecessor-version":[{"id":248584,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/posts\/248533\/revisions\/248584"}],"wp:attachment":[{"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/media?parent=248533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/categories?post=248533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/tags?post=248533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}