{"id":255692,"date":"2023-11-22T22:00:33","date_gmt":"2023-11-22T21:00:33","guid":{"rendered":"https:\/\/montedellevigne.it\/?p=255692"},"modified":"2023-11-25T12:12:57","modified_gmt":"2023-11-25T11:12:57","slug":"vini-delicatessen-emiliane-a-milano","status":"publish","type":"post","link":"https:\/\/montedellevigne.it\/it\/vini-delicatessen-emiliane-a-milano\/","title":{"rendered":"Da A&#038;Co, vini e delicatessen Emiliane si incontrano a Milano"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.0&#8243; background_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/montedellevigne.it\/wp-content\/uploads\/2023\/11\/Degustazione-da-ACo-locandina.jpg&#8221; title_text=&#8221;Degustazione da A&#038;Co locandina&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.23.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Nel cuore di Milano, presso l&#8217;esclusiva enoteca <em>A&amp;Co <\/em>in Via Piero Capponi, si \u00e8 tenuta un&#8217;indimenticabile esperienza sensoriale Emiliana, grazie alla degustazione dei vini Monte delle Vigne assieme alle prelibatezze gastronomiche tipiche della nostra terra. L&#8217;evento \u00e8 stato reso possibile grazie ai &#8220;quattro moschettieri dell&#8217;enologia Milanese&#8221; &#8211; <em>Jean Marc<\/em>, <em>Angelo<\/em>, <em>Tommaso<\/em> e <em>Terry<\/em> &#8211; e all&#8217;instancabile lavoro di <em>Maria Iammatteo<\/em>, volto di Monte delle Vigne a Milano.<\/p>\n<p>L&#8217;atmosfera dell&#8217;enoteca <em>A&amp;Co<\/em>, rinomata per la sua selezione di vini pregiati, ha fornito il contesto perfetto per un&#8217;esperienza di degustazione unica. I partecipanti hanno avuto l&#8217;opportunit\u00e0 di immergersi nella cultura enologica ed enogastronomica dell&#8217;Emilia-Romagna, scoprendo i tesori nascosti di questo <em>terroir<\/em> unico.<\/p>\n<p>La degustazione ha preso il via con <a href=\"https:\/\/montedellevigne.it\/negozio\/vini\/lambrusco\/i-calanchi\/\">I Calanchi<\/a> &#8211; 100% Lambrusco Maestri -, abbinato alla classica mortadella bolognese; poi gli invitati hanno potuto assaggiare <a href=\"https:\/\/montedellevigne.it\/negozio\/vini\/il-chiuso-cabernet-franc\/\">Il Chiuso<\/a> &#8211; Cabernet Franc &#8211; assieme allo strolghino (il piccolo salame derivato dalle\u00a0rifilature magre del culatello e del fiocco) e il salame gentile; infine, il &#8220;re della cantina&#8221; <a href=\"https:\/\/montedellevigne.it\/vino\/nabucco\/\">Nabucco<\/a>\u00a0&#8211; 90% Barbera, 10% Merlot nella versione nuova annata 2020 &#8211; ha stupito gli intervenuti grazie al <em>pairing<\/em> con scaglie di Parmigiano Reggiano 34 mesi, sia &#8220;a crudo&#8221; che con un tocco di confettura di prugne.<\/p>\n<p>L&#8217;evento \u00e8 stato un&#8217;occasione straordinaria per apprezzare la ricchezza e la variet\u00e0 dei sapori dell&#8217;Emilia-Romagna, non solo attraverso i vini Monte delle Vigne, ma anche grazie alle &#8220;chicche gastronomiche&#8221; che hanno deliziato i presenti. Il Parmigiano Reggiano, con la sua <em>texture<\/em> granulosa e il sapore intenso, ha conquistato i palati dei partecipanti, mentre il salame gentile, lo strolghino e la mortadella hanno portato in zona Piazza Wagner il gusto autentico e inconfondibile della <em>pastorale life <\/em>Emiliana. Gli abbinamenti tra vino e cibo, sapientemente orchestrati dallo staff di <em>A&amp;Co<\/em>, hanno esaltato le caratteristiche di entrambi, creando armonie gustative indimenticabili.<\/p>\n<p>La passione e l&#8217;entusiasmo di <em>Maria<\/em> &#8211; per una sera anche in versione &#8220;affetta-salumi&#8221; e &#8220;porzionatrice di Parmigiano&#8221; &#8211; hanno reso la situazione coinvolgente e allo stesso tempo spensierata.<\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=&#8221;255699,255700,255701,255702,255709,255711,255712,255713,255714,255715,255716,255717,255718&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][et_pb_video src=&#8221;https:\/\/montedellevigne.it\/wp-content\/uploads\/2023\/11\/MdV-tasting-at-ACo.mp4&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel cuore di Milano, presso l&#8217;esclusiva enoteca A&amp;Co in Via Piero Capponi, si \u00e8 tenuta un&#8217;indimenticabile esperienza sensoriale Emiliana, grazie alla degustazione dei vini Monte delle Vigne assieme alle prelibatezze gastronomiche tipiche della nostra terra. L&#8217;evento \u00e8 stato reso possibile grazie ai &#8220;quattro moschettieri dell&#8217;enologia Milanese&#8221; &#8211; Jean Marc, Angelo, Tommaso e Terry &#8211; e [&hellip;]<\/p>\n","protected":false},"author":2674,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p style=\"text-align: right;\">26 Ottobre 2022<\/p><p style=\"text-align: center;\"><em>\"Nabucco<\/em> <em>non celebra solo i suoi primi trent\u2019anni, ma anche l\u2019inizio di un lungo cammino che ha visto la nostra <\/em><em>azienda protagonista della produzione di vini biologici di qualit\u00e0, nel rispetto della sostenibilit\u00e0 e sostenuti da una forte passione, a partire da vitigni radicati nel territorio, e dal peculiare carattere fermo in controtendenza con i vini frizzanti tipici di questa terra. Una festa per il successo di un vino quindi che, fin dal nome, trasmette energia e tenacia, gli stessi valori dell\u2019opera verdiana che ha debuttato alla Scala di Milano<\/em><em> nel 1842\".<\/em><\/p><p style=\"text-align: center;\"><em>Paolo Pizzarotti<\/em><\/p><p><img class=\"wp-image-244534 aligncenter\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/f87e29ad-d34e-47f2-9b5c-9133a520e769-225x300.jpg\" alt=\"\" width=\"197\" height=\"262\" \/><\/p><p><strong><em>Nabucco<\/em><\/strong>, il vino simbolo dell\u2019azienda e<strong><em>\u00a0<\/em><\/strong>prodotto esclusivamente con uve Barbera e Merlot, celebra quest\u2019anno <strong>le trenta vendemmie<\/strong>. <em>Nabucco<\/em> \u00e8 una sintesi profonda dell\u2019identit\u00e0 della cantina: \u00e8 <strong>il primo vino<\/strong> nato in casa Monte delle Vigne, nel 1992, ed \u00e8 <strong>il primo rosso fermo<\/strong> realizzato a Parma, un territorio dove per tradizione dominano i frizzanti. Il nome del vino \u00e8 un omaggio al territorio parmense e al suo carattere legato al mondo lirico come citt\u00e0 della musica.<\/p><p>I vigneti con cui viene prodotto Nabucco hanno dai nove ai trent\u2019anni di et\u00e0 e crescono su <strong>terreni calcareo argillosi<\/strong> ad un\u2019altitudine di <strong>200\/300 metri<\/strong>. L\u2019<strong>uva Barbera <\/strong>viene selezionata e raccolta a mano e macera, dopo la fermentazione a 32\u00b0, \u00a030 giorni sulle bucce e <strong>affina poi 12\/14 mesi<\/strong><\/p><p>\u00a0<\/p><p style=\"text-align: left;\">Per festeggiare questo suo importante traguardo lo abbiamo reso protagonista di un pranzo esclusivo in una <strong>verticale senza tempo<\/strong>: <strong>una selezione di 5 annate<\/strong>, rappresentative delle migliori espressioni del percorso di Nabucco, in un gioco perfetto di sapori ed equilibri studiato dallo Chef de <strong>\"Il Luogo di Aimo e Nadia\"<\/strong><\/p><p><img class=\"wp-image-244700 aligncenter\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/12\/MONTE-DELLE-VIGNE-Nabucco-menu_pages-to-jpg-0001-300x206.jpg\" alt=\"\" width=\"172\" height=\"118\" \/><\/p><p style=\"text-align: center;\"><strong>Ripercorri con noi le tappe di questo <\/strong><\/p><p style=\"text-align: center;\"><strong>indimenticabile viaggio<\/strong><\/p>[caption id=\"attachment_244604\" align=\"aligncenter\" width=\"300\"]<img class=\"wp-image-244604 size-medium\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/cce2cb1f-2a61-460b-96ff-660c7e95e658-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> Cicerchie dei Monti Dauni con marasciuolo, oliva Nolca e lampascioni all\u2019aceto di lamponi - Nabucco 2018[\/caption][caption id=\"attachment_244602\" align=\"aligncenter\" width=\"300\"]<img class=\"wp-image-244602 size-medium\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/5bb5df04-d249-4964-b7b8-30ca7270baf5-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> Mousse di funghi porcini su pan brioche caldo - Nabucco 2015[\/caption][caption id=\"attachment_244600\" align=\"aligncenter\" width=\"300\"]<img class=\"wp-image-244600 size-medium\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/00a994aa-6547-44c9-a3af-ad9b2f149683-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> Tortelli farciti di ossobuco di Fassona e midollo e il suo ristretto allo zafferano sardo e parmigiano - Nabucco 2011[\/caption][caption id=\"attachment_244603\" align=\"aligncenter\" width=\"300\"]<img class=\"wp-image-244603 size-medium\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/a53ef983-2587-433a-aeb8-0c9311d91cc9-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> tortelli farciti di ossobuco di Fassona e midollo e il suo ristretto allo zafferano sardo e parmigiano - Nabucco 2005[\/caption][caption id=\"attachment_244601\" align=\"aligncenter\" width=\"300\"]<img class=\"wp-image-244601 size-medium\" src=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/4cd15962-6ce4-4d5b-9433-89226abb8ac4-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> Anatra Apicius affumicata alle spezie con salsa di seppie - Nabucco 1998[\/caption]<p>\u00a0<\/p><p style=\"text-align: center;\"><strong>APPROFONDIMENTI<\/strong><\/p><p style=\"text-align: center;\"><a href=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/MONTE-DELLE-VIGNE-Nabucco-menu.pdf\" target=\"_blank\" rel=\"noopener\">MONTE DELLE VIGNE & iL LUOGO - Men\u00f9<\/a><\/p><p style=\"text-align: center;\"><a href=\"https:\/\/montedellevigne.it\/wp-content\/uploads\/2022\/10\/ANDAMENTO-ANNATE_def.pdf\">NABUCCO - ANDAMENTO ANNATE<\/a><\/p><p style=\"text-align: center;\"><strong>RASSEGNA STAMPA<\/strong><\/p><p style=\"text-align: center;\"><a href=\"https:\/\/www.civiltadelbere.com\/nabucco-di-monte-delle-vigne-racconta-i-suoi-primi-30-anni\/\" target=\"_blank\" rel=\"noopener\">CIVILTA' DEL BERE<\/a><\/p><p style=\"text-align: center;\"><a href=\"https:\/\/www.ilgolosario.it\/it\/monte-delle-vigne-lo-splendore-della-barbera\" target=\"_blank\" rel=\"noopener\">IL GOLOSARIO<\/a><\/p><p style=\"text-align: center;\"><a href=\"https:\/\/www.ioeilvino.it\/monte-delle-vigne-30-anni-di-nabucco\/\" target=\"_blank\" rel=\"noopener\">IOEILVINO.IT<\/a><\/p>","_et_gb_content_width":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-255692","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Da A&amp;Co, vini e delicatessen Emiliane si incontrano a Milano - Monte delle Vigne<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Da A&amp;Co, vini e delicatessen Emiliane si incontrano a Milano - Monte delle Vigne\" \/>\n<meta property=\"og:description\" content=\"Nel cuore di Milano, presso l&#039;esclusiva enoteca A&amp;Co in Via Piero Capponi, si \u00e8 tenuta un&#039;indimenticabile esperienza sensoriale Emiliana, grazie alla degustazione dei vini Monte delle Vigne assieme alle prelibatezze gastronomiche tipiche della nostra terra. L&#039;evento \u00e8 stato reso possibile grazie ai &quot;quattro moschettieri dell&#039;enologia Milanese&quot; - Jean Marc, Angelo, Tommaso e Terry - e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montedellevigne.it\/it\/vini-delicatessen-emiliane-a-milano\/\" \/>\n<meta property=\"og:site_name\" content=\"Monte delle Vigne\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-22T21:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-25T11:12:57+00:00\" \/>\n<meta name=\"author\" content=\"mdv-editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mdv-editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/vini-delicatessen-emiliane-a-milano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/vini-delicatessen-emiliane-a-milano\\\/\"},\"author\":{\"name\":\"mdv-editor\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#\\\/schema\\\/person\\\/97c95fefce892f1b82cf733eb48064fd\"},\"headline\":\"Da A&#038;Co, vini e delicatessen Emiliane si incontrano a Milano\",\"datePublished\":\"2023-11-22T21:00:33+00:00\",\"dateModified\":\"2023-11-25T11:12:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/vini-delicatessen-emiliane-a-milano\\\/\"},\"wordCount\":499,\"publisher\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/vini-delicatessen-emiliane-a-milano\\\/\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/vini-delicatessen-emiliane-a-milano\\\/\",\"name\":\"Da A&Co, vini e delicatessen Emiliane si incontrano a Milano - Monte delle Vigne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#website\"},\"datePublished\":\"2023-11-22T21:00:33+00:00\",\"dateModified\":\"2023-11-25T11:12:57+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montedellevigne.it\\\/vini-delicatessen-emiliane-a-milano\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/\",\"name\":\"Monte delle Vigne\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#organization\",\"name\":\"Monte delle Vigne\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/montedellevigne.it\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/MdV-logo-trasp-no-foglia.png\",\"contentUrl\":\"https:\\\/\\\/montedellevigne.it\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/MdV-logo-trasp-no-foglia.png\",\"width\":393,\"height\":200,\"caption\":\"Monte delle Vigne\"},\"image\":{\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/#\\\/schema\\\/person\\\/97c95fefce892f1b82cf733eb48064fd\",\"name\":\"mdv-editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g\",\"caption\":\"mdv-editor\"},\"url\":\"https:\\\/\\\/montedellevigne.it\\\/it\\\/author\\\/mdv-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Da A&Co, vini e delicatessen Emiliane si incontrano a Milano - Monte delle Vigne","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Da A&Co, vini e delicatessen Emiliane si incontrano a Milano - Monte delle Vigne","og_description":"Nel cuore di Milano, presso l'esclusiva enoteca A&amp;Co in Via Piero Capponi, si \u00e8 tenuta un'indimenticabile esperienza sensoriale Emiliana, grazie alla degustazione dei vini Monte delle Vigne assieme alle prelibatezze gastronomiche tipiche della nostra terra. L'evento \u00e8 stato reso possibile grazie ai \"quattro moschettieri dell'enologia Milanese\" - Jean Marc, Angelo, Tommaso e Terry - e [&hellip;]","og_url":"https:\/\/montedellevigne.it\/it\/vini-delicatessen-emiliane-a-milano\/","og_site_name":"Monte delle Vigne","article_published_time":"2023-11-22T21:00:33+00:00","article_modified_time":"2023-11-25T11:12:57+00:00","author":"mdv-editor","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"mdv-editor","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montedellevigne.it\/vini-delicatessen-emiliane-a-milano\/#article","isPartOf":{"@id":"https:\/\/montedellevigne.it\/vini-delicatessen-emiliane-a-milano\/"},"author":{"name":"mdv-editor","@id":"https:\/\/montedellevigne.it\/it\/#\/schema\/person\/97c95fefce892f1b82cf733eb48064fd"},"headline":"Da A&#038;Co, vini e delicatessen Emiliane si incontrano a Milano","datePublished":"2023-11-22T21:00:33+00:00","dateModified":"2023-11-25T11:12:57+00:00","mainEntityOfPage":{"@id":"https:\/\/montedellevigne.it\/vini-delicatessen-emiliane-a-milano\/"},"wordCount":499,"publisher":{"@id":"https:\/\/montedellevigne.it\/it\/#organization"},"articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/montedellevigne.it\/vini-delicatessen-emiliane-a-milano\/","url":"https:\/\/montedellevigne.it\/vini-delicatessen-emiliane-a-milano\/","name":"Da A&Co, vini e delicatessen Emiliane si incontrano a Milano - Monte delle Vigne","isPartOf":{"@id":"https:\/\/montedellevigne.it\/it\/#website"},"datePublished":"2023-11-22T21:00:33+00:00","dateModified":"2023-11-25T11:12:57+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montedellevigne.it\/vini-delicatessen-emiliane-a-milano\/"]}]},{"@type":"WebSite","@id":"https:\/\/montedellevigne.it\/it\/#website","url":"https:\/\/montedellevigne.it\/it\/","name":"Monte delle Vigne","description":"","publisher":{"@id":"https:\/\/montedellevigne.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montedellevigne.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/montedellevigne.it\/it\/#organization","name":"Monte delle Vigne","url":"https:\/\/montedellevigne.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/montedellevigne.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/montedellevigne.it\/wp-content\/uploads\/2020\/05\/MdV-logo-trasp-no-foglia.png","contentUrl":"https:\/\/montedellevigne.it\/wp-content\/uploads\/2020\/05\/MdV-logo-trasp-no-foglia.png","width":393,"height":200,"caption":"Monte delle Vigne"},"image":{"@id":"https:\/\/montedellevigne.it\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/montedellevigne.it\/it\/#\/schema\/person\/97c95fefce892f1b82cf733eb48064fd","name":"mdv-editor","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea134359f60ac4deca1a293a0f4a6af1922037abc26ccce1ad501d695dd410a9?s=96&d=blank&r=g","caption":"mdv-editor"},"url":"https:\/\/montedellevigne.it\/it\/author\/mdv-editor\/"}]}},"_links":{"self":[{"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/posts\/255692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/users\/2674"}],"replies":[{"embeddable":true,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/comments?post=255692"}],"version-history":[{"count":11,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/posts\/255692\/revisions"}],"predecessor-version":[{"id":255725,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/posts\/255692\/revisions\/255725"}],"wp:attachment":[{"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/media?parent=255692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/categories?post=255692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montedellevigne.it\/it\/wp-json\/wp\/v2\/tags?post=255692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}